{"id":2735,"date":"2021-05-13T11:22:00","date_gmt":"2021-05-13T15:22:00","guid":{"rendered":"https:\/\/comicdominicano.com\/?p=2735"},"modified":"2025-03-18T11:45:48","modified_gmt":"2025-03-18T15:45:48","slug":"invincible-una-catarsis-superheroica-moderna","status":"publish","type":"post","link":"https:\/\/comicdominicano.com\/en\/invincible-una-catarsis-superheroica-moderna\/","title":{"rendered":"&#8221;Invincible&#8221;, una catarsis superheroica moderna"},"content":{"rendered":"[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<p><\/p>\n<p>Arist\u00f3teles dec\u00eda que la catarsis es la facultad de la tragedia de redimir al espectador al verse proyectado en los personajes de una obra. Es por esto que creo que los imperfectos dioses griegos y su tendencia a las bajas pasiones son la inspiraci\u00f3n de las mejores historias presentes en las obras que relatan las tragedias y triunfos de los superh\u00e9roes modernos.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Dejando esto claro, en mi sesgada opini\u00f3n, creo que \u00bbInvincible\u00bb (Tanto el c\u00f3mic como la serie en Amazon Prime Video) es el punto m\u00e1s alto que han alcanzado las ya tan populares obras que cuentan historias de Superh\u00e9roes. \u00bfNo me crees? Pues contraargumentar\u00e9 con unas cuantas preguntas:<\/p>\n<p><\/p>\n<p><\/p>\n<ol class=\"wp-block-list\">\n<li>\u00bfEn qu\u00e9 otra obra de superh\u00e9roes moderna podemos encontrar tragedias, triunfos y humor reminiscentes a lo que Pascu y Rodri no paran de relatar en sus canciones?<\/li>\n<li>\u00bfExiste otra obra de superh\u00e9roes que adem\u00e1s de tocar temas sociales relevantes con un estilo de dibujo fresco y colores brillantes es capaz de balancear la tragedia con la esperanza de una manera coherente?<\/li>\n<li>\u00bfAlguna otra obra de superh\u00e9roes logra parodiar todos los tropos y clich\u00e9s que DC y Marvel no se cansan de explotar en sus historias de superh\u00e9roes sin dejar de contar una historia emocionante?<\/li>\n<\/ol>\n<p><\/p>\n<p><\/p>\n<p>A quienes respondieron \u00bbAnimal-Man\u00bb de Grant Morrison, \u00bbMiracle Man\u00bb de Alan Moore o cualquier c\u00f3mic de Matt Kindt y Jeff Lemire para Valiant, debo decirles que tienen muy buen gusto.<\/p>\n<p><\/p>\n<p><\/p>\n<div id=\"attachment_31715\" class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Animal-Man.jpg\" alt=\"Animal Man\" class=\"wp-image-31715\" \/><br \/>\n<figcaption>\u00bbAnimal Man\u00bb de Grant Morrison, otro de esos c\u00f3mics que trazan paradigmas en el \u00e1mbito de los superheroes.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>De todos modos, aunque quienes s\u00f3lo han visto la serie no conectar\u00e1n con estas preguntas como quienes ya leyeron el c\u00f3mic, si tomamos en cuenta que esta obra ya fue renovada para 2 temporadas adicionales, pueden usar estas preguntas como un punto de referencia sin spoilers de lo que a\u00fan le queda por contar a la que opino es la m\u00e1s grande obra de Robert Kirkman y Cory Walker (Lo siento, no soy fan de los zombies ni de Ant-Man).<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">\u00bfDe qu\u00e9 trata Invincible?<\/h2>\n<p><\/p>\n<p><\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Invincible-amazon-invincible-comic-robert-kirkman.jpg\" alt=\"Invincible Amazon Video Prime\" class=\"wp-image-31716\" \/><\/figure>\n<p><\/p>\n<p><\/p>\n<p>Seg\u00fan la descripci\u00f3n que da Amazon Prime Video de esto trata Invincible:<\/p>\n<p><\/p>\n<p><\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><br \/>Mark Grayson hereda superpoderes a los diecisiete a\u00f1os y se une a su padre como uno de los mayores h\u00e9roes de la Tierra. Todos sus sue\u00f1os se hacen realidad, hasta que un evento impactante lo cambia todo.<br \/><br \/>-Amazon Prime Video<\/p>\n<\/blockquote>\n<p><\/p>\n<p><\/p>\n<p>Pero, si nos vamos al Volumen 1 del c\u00f3mic en que est\u00e1 basada la serie, nos encontraremos con esta similar pero, en mi opini\u00f3n, m\u00e1s atractiva sinopsis:<\/p>\n<p><\/p>\n<p><\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Descubre la serie de superh\u00e9roes que no se parece a nada que hayas le\u00eddo. Cuando Mark Grayson hereda sus superpoderes a los diecisiete a\u00f1os, es un sue\u00f1o hecho realidad hasta que aprende que ser un h\u00e9roe no es tan blanco y negro como los c\u00f3mics que le\u00eda de ni\u00f1o. Del visionario creador Robert Kirman (The Walking Dead), junto con los aclamados artistas Cory Walker y Ryan Ottley.<\/p>\n<p>-Invincible Volumen 1, Family Matters<\/p>\n<\/blockquote>\n<p><\/p>\n<p><\/p>\n<p>Como dato curioso, si algo amo del subt\u00edtulo del volumen 1 (Ejemplares #1 al #4) es su doble significado que, hasta donde s\u00e9, no puede ser emulado en espa\u00f1ol:<\/p>\n<p><\/p>\n<p><\/p>\n<ul class=\"wp-block-list\">\n<li>La familia importa.<\/li>\n<li>Asuntos familiares.<\/li>\n<\/ul>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">\u00bbInvincible\u00bb como heredero del hero\u00edsmo moderno<\/h2>\n<p><\/p>\n<p><\/p>\n<div id=\"attachment_31717\" class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Invincible-vs-Superboy-Prime.jpg\" alt=\"Invincible vs Superboy Prime\" class=\"wp-image-31717\" \/><br \/>\n<figcaption>Invincible vs Superboy Prime. Lo siento, esto nunca pas\u00f3.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>Cuando le\u00ed \u00bbKingdom Come\u00bb de Mark Waid pens\u00e9 que ninguna otra obra de arte secuencial lograr\u00eda estremecerme tan profundamente. Su emp\u00e1tica historia (narrada a trav\u00e9s de las bell\u00edsimas ilustraciones de Alex Ross) logr\u00f3 que incluso a\u00f1os despu\u00e9s de leerla sienta que me ha cambiado para bien.\u00a0<\/p>\n<p><\/p>\n<p><\/p>\n<p>Pero en toda su majestuosidad, \u00bbKingdom Come\u00bb es una historia que s\u00f3lo lograr\u00eda conectar con quienes tienen a\u00f1os enamorados de los ideales que representan iconos de la cultura pop como Superman, Batman y la Mujer Maravilla, \u00bfc\u00f3mo puedo catalogar a esta obra maestra como una catarsis superheroica\u00a0<strong>moderna<\/strong>\u00a0si no puedo introducirla eficientemente a las nuevas generaciones?\u00a0<\/p>\n<p><\/p>\n<p><\/p>\n<div id=\"attachment_31718\" class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Kingdom-Come-Mark-Waid.jpg\" alt=\"Kingdom Come Mark Waid\" class=\"wp-image-31718\" \/><br \/>\n<figcaption>\u00bbKingdom Come\u00bb, escrito por Mark Waid, arte de Alex Ross.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>El mayor problema de los c\u00f3mics de superheroes tradicionales es que su alcance ha sido fuertemente limitado por obligar a nuevos lectores a conocer 80 a\u00f1os de historias publicadas por decenas de autores diferentes y repletas de errores de continuidad. S\u00ed, \u00bbKingdom Come\u00bb es t\u00e9cnicamente una historia individual que no depende del canon moderno, pero debemos preguntarnos:\u00a0<\/p>\n<p><\/p>\n<p><\/p>\n<p>Si alguien que nunca en su vida ha le\u00eddo sobre Superman lee \u00bbKingdom Come\u00bb \u00bfser\u00e1 impactado de la misma forma por esta obra que por \u00bbInvincible\u00bb?<\/p>\n<p><\/p>\n<p><\/p>\n<p>No voy a decir que, hasta cierto punto, alguien que no conoce los tropos tradicionales de los c\u00f3mics de superheroes no enfrentar\u00e1 los mismos problemas de conexi\u00f3n con \u00bbInvincible\u00bb, pero entiendo que el enfoque estilo Manga de \u00bbInvincible\u00bb (al contar una historia con una conclusi\u00f3n definida) mitiga bastante el problema de la d\u00e9bil conexi\u00f3n con nuevos lectores.<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Una catarsis superheroica moderna<\/h2>\n<p><\/p>\n<p><\/p>\n<p>Como una representaci\u00f3n menos rom\u00e1ntica del superh\u00e9roe moderno, \u00bbInvincible\u00bb\u00a0 logra plasmar las vulnerabilidades que hicieron tan interesantes al pante\u00f3n de dioses griegos que algunos catalogan como los padres espirituales de los superheroes modernos. Algunos ejemplos de estas vulnerabilidades ya han sido representadas en el mundo del c\u00f3mic de superh\u00e9roes a trav\u00e9s de los a\u00f1os en situaciones como:<\/p>\n<p><\/p>\n<p><\/p>\n<ul class=\"wp-block-list\">\n<li>El alcoholismo de Tony Stark.<\/li>\n<li>Los problemas maritales de Hank Pym.<\/li>\n<li>La ca\u00f3tica y precaria vida adolescente de Peter Parker.<\/li>\n<li>La adicci\u00f3n a las drogas de Speedy.<\/li>\n<\/ul>\n<p><\/p>\n<p><\/p>\n<p>A\u00fan as\u00ed, cuando \u00bbInvincible\u00bb presenta a sus protagonistas enfrentando vulnerabilidades como estas, Robert Kirkman logra que conectar con esta historia a trav\u00e9s de las tragedias que sufren personajes como Invincible y Atom Eve no se sienta anticuado.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Con esto no quiero decir que todos los c\u00f3mics de superheroes tradicionales son anticuados, pero obviando el formato novela gr\u00e1fica al estilo de \u00bbBatman: White Knight\u00bb de Sean Murphy o \u00bbWonder Woman: Dead Earth\u00bb de Daniel Warren Johnson, los c\u00f3mics publicados como fasc\u00edculos individuales mensualmente son muy elusivos a la hora de presentarnos con arcos argumentales que valgan la pena.<\/p>\n<p><\/p>\n<p><\/p>\n<div id=\"attachment_31719\" class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Wonder-Woman-Dead-Earth.jpg\" alt=\"Wonder Woman Dead Earth\" class=\"wp-image-31719\" \/><br \/>\n<figcaption>\u00bbWonder Woman: Dead Earth\u00bb escrita e ilustrada por Daniel Warren Johnson<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>La mayor\u00eda de las veces, seguir los arcos argumentales narrados en estos fasc\u00edculos termina siendo una loter\u00eda en la que personalmente prefiero no participar hasta que cada arco llegue a una conclusi\u00f3n relevante. La excepci\u00f3n a esta regla, ir\u00f3nicamente, son la mayor\u00eda de los trabajos publicados por Image C\u00f3mics.<\/p>\n<p><\/p>\n<p><\/p>\n<p>En contraste, debido a la diversidad de temas tratados en \u00bbInvincible\u00bb, admito que no se sinti\u00f3 inorg\u00e1nico comprar cada fasc\u00edculo cuando el c\u00f3mic a\u00fan estaba en emisi\u00f3n.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Exactamente lo mismo pas\u00f3 cuando vi por primera vez la serie animada que adapta a esta obra. Incluso sabiendo c\u00f3mo termina todo, la actuaci\u00f3n de voz de actores como Steven Yeun (Invincible) y J.K. Simmons (Onmiman) agregaron una nueva dimensi\u00f3n a la serie que no me dej\u00f3 perderme un s\u00f3lo cap\u00edtulo de la 1ra temporada.<\/p>\n<p><\/p>\n<p><\/p>\n<div id=\"attachment_31720\" class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Invincible-Voice-Actors.jpg\" alt=\"Invincible Voice Actors\" class=\"wp-image-31720\" \/><br \/>\n<figcaption>J.K. Simmons y Steven Yeun, actores de voz de Omniman e Invincible respectivamente.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>Como dato curioso, el tono de la serie animada es ligeramente m\u00e1s serio que el del c\u00f3mic, en este \u00faltimo hay bastantes chistes que me hicieron re\u00edr bastante en su momento.<\/p>\n<p><\/p>\n<p><\/p>\n<p>He contrastado a \u00bbInvincible\u00bb con sus contrapartes innumerables veces a trav\u00e9s de este art\u00edculo, todo esto con el objetivo de alejarme de los spoilers. A\u00fan as\u00ed no puedo concluir sin aclarar los dos tipos de catarsis que intente exponer en este art\u00edculo:<\/p>\n<p><\/p>\n<p><\/p>\n<ol class=\"wp-block-list\">\n<li><strong>La catarsis como momento purificador para el lector dentro de una obra en especifico:<\/strong>\u00a0\u00bbKingdom Come\u00bb tiene el dialogo final entre el pastor Norman McCay y Superman en las naciones unidas, \u00bbThe Dark Knight Returns\u00bb de Frank Miller tiene, entre varias otras, el enfrentamiento final entre Superman y Batman, \u00bbJupiter\u2019s Legacy\u00bb de Mark Millar tiene la redenci\u00f3n de Skyfox frente a su familia, la lista podr\u00eda seguir casi indefinidamente, pero por el momento la dejaremos hasta aqu\u00ed.<\/li>\n<li><strong>La catarsis como hito en la industria del comic: <\/strong>Cuando titul\u00e9 este art\u00edculo, precisamente en esto estaba pensando. Aunque parezca un chiste que casi todos los ejemplares de \u00bbInvincible\u00bb incluyan el subt\u00edtulo: \u00bbEl mejor c\u00f3mic del universo\u00bb, no es broma que al menos en el \u00e1mbito de los superheroes, este c\u00f3mic ha marcado un antes y un despu\u00e9s en un genero que muchos cre\u00edamos tenia poco o nada m\u00e1s que contar.<\/li>\n<\/ol>\n<p><\/p>\n<p><\/p>\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Culturageek.com_.ar-Invincible-1-1.jpg\" alt=\"Invincible volando por los cielos de Robert Kirkman\" class=\"wp-image-31721\" \/><\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>La catarsis de \u00bbInvincible\u00bb como hito en la industria se traduce a una obra de arte secuencial superheroica tan ambiciosa que me atrevo a decir es a los superheroes en el c\u00f3mic lo que \u00bbSaga\u00bb de Brian K. Vaughan y Fiona Staples es a la ciencia ficci\u00f3n\/fantasia en el mismo medio.<\/p>\n<p><\/p>\n<p><\/p>\n<p>No es todos los d\u00edas que en el c\u00f3mic norteamericano se ven obras de tan alto perfil con autores que tengan la determinaci\u00f3n para trabajar con el compromiso que Kirkman y Walker lograron.<\/p>\n<p><\/p>\n<p><\/p>\n<p>En honor a esto, los dejo con esta frase del autor de &#8221;Wonder Woman: Dead Earth&#8221;, Daniel Warren Johnson:\u00a0<\/p>\n<p><\/p>\n<p><\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Quiero que m\u00e1s artistas se esfuercen como lo hacen muchos artistas de manga, sobre todo en lo que respecta a la acci\u00f3n y la energ\u00eda en las p\u00e1ginas.<\/p>\n<p>Veo que cada vez m\u00e1s artistas empiezan a integrar esto en sus p\u00e1ginas, lo que me entusiasma de cara al futuro, independientemente de que los lectores lo acepten o no.<\/p>\n<p>Dir\u00e9 que ahora que llevo muchos a\u00f1os leyendo manga, estoy empezando a estudiar con m\u00e1s intensidad a los viejos maestros, como Kirby y Simonson.<\/p>\n<p>Intento conectar lo mejor de ambos mundos, combinando la intensidad y el peso del aspecto de Kirby con la precisi\u00f3n y la din\u00e1mica de Otomo.<\/p>\n<p>Son objetivos elevados, lo s\u00e9, pero me hacen trabajar duro.<\/p>\n<p>-Daniel Warren Johnson<\/p>\n<\/blockquote>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Conclusi\u00f3n<\/h2>\n<p><\/p>\n<p><\/p>\n<p>Que un momento en un c\u00f3mic represente o no una catarsis para ti es algo muy personal. Al menos en mi caso, me siento honrado de haber tenido tantas experiencias maravillosas leyendo c\u00f3mics.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Por otro lado, que un c\u00f3mic logre convertirse en una catarsis superheroica moderna requiere que la obra se convierta en un paradigma para las nuevas generaciones de lectores y artistas secuenciales que consumir\u00e1n y crearan los c\u00f3mics del futuro respectivamente.<\/p>\n<p><!-- Thanks Jearel and Checo --><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Arist\u00f3teles dec\u00eda que la catarsis es la facultad de la tragedia de redimir al espectador al verse proyectado en los personajes de una obra. Es por esto que creo que los imperfectos dioses griegos y su tendencia a las bajas pasiones son la inspiraci\u00f3n de las mejores historias presentes en las obras que relatan las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>Arist\u00f3teles dec\u00eda que la catarsis es la facultad de la tragedia de redimir al espectador al verse proyectado en los personajes de una obra. Es por esto que creo que los imperfectos dioses griegos y su tendencia a las bajas pasiones son la inspiraci\u00f3n de las mejores historias presentes en las obras que relatan las tragedias y triunfos de los superh\u00e9roes modernos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dejando esto claro, en mi sesgada opini\u00f3n, creo que \u00bbInvincible\u00bb (Tanto el c\u00f3mic como la serie en Amazon Prime Video) es el punto m\u00e1s alto que han alcanzado las ya tan populares obras que cuentan historias de Superh\u00e9roes. \u00bfNo me crees? Pues contraargumentar\u00e9 con unas cuantas preguntas:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><li>\u00bfEn qu\u00e9 otra obra de superh\u00e9roes moderna podemos encontrar tragedias, triunfos y humor reminiscentes a lo que Pascu y Rodri no paran de relatar en sus canciones?<\/li><li>\u00bfExiste otra obra de superh\u00e9roes que adem\u00e1s de tocar temas sociales relevantes con un estilo de dibujo fresco y colores brillantes es capaz de balancear la tragedia con la esperanza de una manera coherente?<\/li><li>\u00bfAluna otra obra de superh\u00e9roes logra parodiar todos los tropos y clich\u00e9s que DC y Marvel no se cansan de explotar en sus historias de superh\u00e9roes sin dejar de contar una historia emocionante?<\/li><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>A quienes respondieron \u00bbAnimal-Man\u00bb de Grant Morrison, \u00bbMiracle Man\u00bb de Alan Moore o cualquier c\u00f3mic de Matt Kindt y Jeff Lemire para Valiant, debo decirles que tienen muy buen gusto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":31715} -->\n<div id=\"attachment_31715\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Animal-Man.jpg\" alt=\"Animal Man\" class=\"wp-image-31715\"\/><figcaption>\u00bbAnimal Man\u00bb de Grant Morrison, otro de esos c\u00f3mics que trazan paradigmas en el \u00e1mbito de los superheroes.<\/figcaption><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>De todos modos, aunque quienes s\u00f3lo han visto la serie no conectar\u00e1n con estas preguntas como quienes ya leyeron el c\u00f3mic, si tomamos en cuenta que esta obra ya fue renovada para 2 temporadas adicionales, pueden usar estas preguntas como un punto de referencia sin spoilers de lo que a\u00fan le queda por contar a la que opino es la m\u00e1s grande obra de Robert Kirkman y Cory Walker (Lo siento, no soy fan de los zombies ni de Ant-Man).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>\u00bfDe qu\u00e9 trata Invincible?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:image {\"id\":31716} -->\n<figure class=\"wp-block-image\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Invincible-amazon-invincible-comic-robert-kirkman.jpg\" alt=\"Invincible Amazon Video Prime\" class=\"wp-image-31716\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Seg\u00fan la descripci\u00f3n que da Amazon Prime Video de esto trata Invincible:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><p><br>Mark Grayson hereda superpoderes a los diecisiete a\u00f1os y se une a su padre como uno de los mayores h\u00e9roes de la Tierra. Todos sus sue\u00f1os se hacen realidad, hasta que un evento impactante lo cambia todo.<br><br>-Amazon Prime Video<\/p><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Pero, si nos vamos al Volumen 1 del c\u00f3mic en que est\u00e1 basada la serie, nos encontraremos con esta similar pero, en mi opini\u00f3n, m\u00e1s atractiva sinopsis:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><p>Descubre la serie de superh\u00e9roes que no se parece a nada que hayas le\u00eddo. Cuando Mark Grayson hereda sus superpoderes a los diecisiete a\u00f1os, es un sue\u00f1o hecho realidad hasta que aprende que ser un h\u00e9roe no es tan blanco y negro como los c\u00f3mics que le\u00eda de ni\u00f1o. Del visionario creador Robert Kirman (The Walking Dead), junto con los aclamados artistas Cory Walker y Ryan Ottley.<\/p><p>-Invincible Volumen 1, Family Matters<\/p><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Como dato curioso, si algo amo del subt\u00edtulo del volumen 1 (Ejemplares #1 al #4) es su doble significado que, hasta donde s\u00e9, no puede ser emulado en espa\u00f1ol:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>La familia importa.<\/li><li>Asuntos familiares.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading -->\n<h2>\u00bbInvincible\u00bb como heredero del hero\u00edsmo moderno<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":31717} -->\n<div id=\"attachment_31717\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Invincible-vs-Superboy-Prime.jpg\" alt=\"Invincible vs Superboy Prime\" class=\"wp-image-31717\"\/><figcaption>Invincible vs Superboy Prime. Lo siento, esto nunca pas\u00f3.<\/figcaption><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Cuando le\u00ed \u00bbKingdom Come\u00bb de Mark Waid pens\u00e9 que ninguna otra obra de arte secuencial lograr\u00eda estremecerme tan profundamente. Su emp\u00e1tica historia (narrada a trav\u00e9s de las bell\u00edsimas ilustraciones de Alex Ross) logr\u00f3 que incluso a\u00f1os despu\u00e9s de leerla sienta que me ha cambiado para bien.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero en toda su majestuosidad, \u00bbKingdom Come\u00bb es una historia que s\u00f3lo lograr\u00eda conectar con quienes tienen a\u00f1os enamorados de los ideales que representan iconos de la cultura pop como Superman, Batman y la Mujer Maravilla, \u00bfc\u00f3mo puedo catalogar a esta obra maestra como una catarsis superheroica&nbsp;<strong>moderna<\/strong>&nbsp;si no puedo introducirla eficientemente a las nuevas generaciones?&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":31718} -->\n<div id=\"attachment_31718\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Kingdom-Come-Mark-Waid.jpg\" alt=\"Kingdom Come Mark Waid\" class=\"wp-image-31718\"\/><figcaption>\u00bbKingdom Come\u00bb, escrito por Mark Waid, arte de Alex Ross.<\/figcaption><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>El mayor problema de los c\u00f3mics de superheroes tradicionales es que su alcance ha sido fuertemente limitado por obligar a nuevos lectores a conocer 80 a\u00f1os de historias publicadas por decenas de autores diferentes y repletas de errores de continuidad. S\u00ed, \u00bbKingdom Come\u00bb es t\u00e9cnicamente una historia individual que no depende del canon moderno, pero debemos preguntarnos:&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si alguien que nunca en su vida ha le\u00eddo sobre Superman lee \u00bbKingdom Come\u00bb \u00bfser\u00e1 impactado de la misma forma por esta obra que por \u00bbInvincible\u00bb?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>No voy a decir que, hasta cierto punto, alguien que no conoce los tropos tradicionales de los c\u00f3mics de superheroes no enfrentar\u00e1 los mismos problemas de conexi\u00f3n con \u00bbInvincible\u00bb, pero entiendo que el enfoque estilo Manga de \u00bbInvincible\u00bb (al contar una historia con una conclusi\u00f3n definida) mitiga bastante el problema de la d\u00e9bil conexi\u00f3n con nuevos lectores.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Una catarsis superheroica moderna<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Como una representaci\u00f3n menos rom\u00e1ntica del superh\u00e9roe moderno, \u00bbInvincible\u00bb&nbsp; logra plasmar las vulnerabilidades que hicieron tan interesantes al pante\u00f3n de dioses griegos que algunos catalogan como los padres espirituales de los superheroes modernos. Algunos ejemplos de estas vulnerabilidades ya han sido representadas en el mundo del c\u00f3mic de superh\u00e9roes a trav\u00e9s de los a\u00f1os en situaciones como:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>El alcoholismo de Tony Stark.<\/li><li>Los problemas maritales de Hank Pym.<\/li><li>La ca\u00f3tica y precaria vida adolescente de Peter Parker.<\/li><li>La adicci\u00f3n a las drogas de Speedy.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>A\u00fan as\u00ed, cuando \u00bbInvincible\u00bb presenta a sus protagonistas enfrentando vulnerabilidades como estas, Robert Kirkman logra que conectar con esta historia a trav\u00e9s de las tragedias que sufren personajes como Invincible y Atom Eve no se sienta anticuado.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Con esto no quiero decir que todos los c\u00f3mics de superheroes tradicionales son anticuados, pero obviando el formato novela gr\u00e1fica al estilo de \u00bbBatman: White Knight\u00bb de Sean Murphy o \u00bbWonder Woman: Dead Earth\u00bb de Daniel Warren Johnson, los c\u00f3mics publicados como fasc\u00edculos individuales mensualmente son muy elusivos a la hora de presentarnos con arcos argumentales que valgan la pena.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":31719} -->\n<div id=\"attachment_31719\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Wonder-Woman-Dead-Earth.jpg\" alt=\"Wonder Woman Dead Earth\" class=\"wp-image-31719\"\/><figcaption>\u00bbWonder Woman: Dead Earth\u00bb escrita e ilustrada por Daniel Warren Johnson<\/figcaption><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>La mayor\u00eda de las veces, seguir los arcos argumentales narrados en estos fasc\u00edculos termina siendo una loter\u00eda en la que personalmente prefiero no participar hasta que cada arco llegue a una conclusi\u00f3n relevante. La excepci\u00f3n a esta regla, ir\u00f3nicamente, son la mayor\u00eda de los trabajos publicados por Image C\u00f3mics.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En contraste, debido a la diversidad de temas tratados en \u00bbInvincible\u00bb, admito que no se sinti\u00f3 inorg\u00e1nico comprar cada fasc\u00edculo cuando el c\u00f3mic a\u00fan estaba en emisi\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Exactamente lo mismo pas\u00f3 cuando vi por primera vez la serie animada que adapta a esta obra. Incluso sabiendo c\u00f3mo termina todo, la actuaci\u00f3n de voz de actores como Steven Yeun (Invincible) y J.K. Simmons (Onmiman) agregaron una nueva dimensi\u00f3n a la serie que no me dej\u00f3 perderme un s\u00f3lo cap\u00edtulo de la 1ra temporada.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":31720} -->\n<div id=\"attachment_31720\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Invincible-Voice-Actors.jpg\" alt=\"Invincible Voice Actors\" class=\"wp-image-31720\"\/><figcaption>J.K. Simmons y Steven Yeun, actores de voz de Omniman e Invincible respectivamente.<\/figcaption><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Como dato curioso, el tono de la serie animada es ligeramente m\u00e1s serio que el del c\u00f3mic, en este \u00faltimo hay bastantes chistes que me hicieron re\u00edr bastante en su momento.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>He contrastado a \u00bbInvincible\u00bb con sus contrapartes innumerables veces a trav\u00e9s de este art\u00edculo, todo esto con el objetivo de alejarme de los spoilers. A\u00fan as\u00ed no puedo concluir sin aclarar los dos tipos de catarsis que intente exponer en este art\u00edculo:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><li><strong>La catarsis como momento purificador para el lector dentro de una obra en especifico:<\/strong>&nbsp;\u00bbKingdom Come\u00bb tiene el dialogo final entre el pastor Norman McCay y Superman en las naciones unidas, \u00bbThe Dark Knight Returns\u00bb de Frank Miller tiene, entre varias otras, el enfrentamiento final entre Superman y Batman, \u00bbJupiter\u2019s Legacy\u00bb de Mark Millar tiene la redenci\u00f3n de Skyfox frente a su familia, la lista podr\u00eda seguir casi indefinidamente, pero por el momento la dejaremos hasta aqu\u00ed.<br><\/li><li><strong>La catarsis como hito en la industria del comic: <\/strong>Cuando titul\u00e9 este art\u00edculo, precisamente en esto estaba pensando. Aunque parezca un chiste que casi todos los ejemplares de \u00bbInvincible\u00bb incluyan el subt\u00edtulo: \u00bbEl mejor c\u00f3mic del universo\u00bb, no es broma que al menos en el \u00e1mbito de los superheroes, este c\u00f3mic ha marcado un antes y un despu\u00e9s en un genero que muchos cre\u00edamos tenia poco o nada m\u00e1s que contar.<\/li><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":31721,\"className\":\"is-style-default\"} -->\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.geek.com.do\/wp-content\/uploads\/2021\/05\/Culturageek.com_.ar-Invincible-1-1.jpg\" alt=\"Invincible volando por los cielos de Robert Kirkman\" class=\"wp-image-31721\"\/><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>La catarsis de \u00bbInvincible\u00bb como hito en la industria se traduce a una obra de arte secuencial superheroica tan ambiciosa que me atrevo a decir es a los superheroes en el c\u00f3mic lo que \u00bbSaga\u00bb de Brian K. Vaughan y Fiona Staples es a la ciencia ficci\u00f3n\/fantasia en el mismo medio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>No es todos los d\u00edas que en el c\u00f3mic norteamericano se ven obras de tan alto perfil con autores que tengan la determinaci\u00f3n para trabajar con el compromiso que Kirkman y Walker lograron.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En honor a esto, los dejo con esta frase del autor de ''Wonder Woman: Dead Earth'', Daniel Warren Johnson:&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><p>Quiero que m\u00e1s artistas se esfuercen como lo hacen muchos artistas de manga, sobre todo en lo que respecta a la acci\u00f3n y la energ\u00eda en las p\u00e1ginas.<\/p><p>Veo que cada vez m\u00e1s artistas empiezan a integrar esto en sus p\u00e1ginas, lo que me entusiasma de cara al futuro, independientemente de que los lectores lo acepten o no.<\/p><p>Dir\u00e9 que ahora que llevo muchos a\u00f1os leyendo manga, estoy empezando a estudiar con m\u00e1s intensidad a los viejos maestros, como Kirby y Simonson.<\/p><p>Intento conectar lo mejor de ambos mundos, combinando la intensidad y el peso del aspecto de Kirby con la precisi\u00f3n y la din\u00e1mica de Otomo.<\/p><p>Son objetivos elevados, lo s\u00e9, pero me hacen trabajar duro.<\/p><p>-Daniel Warren Johnson<\/p><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2>Conclusi\u00f3n<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Que un momento en un c\u00f3mic represente o no una catarsis para ti es algo muy personal. Al menos en mi caso, me siento honrado de haber tenido tantas experiencias maravillosas leyendo c\u00f3mics.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por otro lado, que un c\u00f3mic logre convertirse en una catarsis superheroica moderna requiere que la obra se convierta en un paradigma para las nuevas generaciones de lectores y artistas secuenciales que consumir\u00e1n y crearan los c\u00f3mics del futuro respectivamente.<\/p>\n<!-- \/wp:paragraph --><!-- Thanks Jearel and Checo -->","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[16,37],"tags":[19,121],"class_list":["post-2735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-secuencial","category-comic-usa","tag-arte-secuencial","tag-invincible"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;&#039;Invincible&#039;&#039;, una catarsis superheroica moderna - Cultura C\u00f3mic RD<\/title>\n<meta name=\"description\" content=\"Catarsis es la facultad de redimir al espectador al proyectarlo en los personajes, &#039;&#039;Invincible&#039;&#039; es un ejemplo de esto en el c\u00f3mic moderno.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comicdominicano.com\/en\/invincible-una-catarsis-superheroica-moderna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;&#039;Invincible&#039;&#039;, una catarsis superheroica moderna - Cultura C\u00f3mic RD\" \/>\n<meta property=\"og:description\" content=\"Catarsis es la facultad de redimir al espectador al proyectarlo en los personajes, &#039;&#039;Invincible&#039;&#039; es un ejemplo de esto en el c\u00f3mic moderno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comicdominicano.com\/en\/invincible-una-catarsis-superheroica-moderna\/\" \/>\n<meta property=\"og:site_name\" content=\"Cultura C\u00f3mic RD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CulturaComicRD\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/culturacomicrd\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-13T15:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T15:45:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comicdominicano.com\/wp-content\/uploads\/2021\/05\/Invincible-una-catarsis-superheroica-moderna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Winser Espinal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@winserespinal\" \/>\n<meta name=\"twitter:site\" content=\"@CulturaComic\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Winser Espinal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/\"},\"author\":{\"name\":\"Winser Espinal\",\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#\\\/schema\\\/person\\\/a5b6cd7bac355962b46feb1abc6ec008\"},\"headline\":\"&#8221;Invincible&#8221;, una catarsis superheroica moderna\",\"datePublished\":\"2021-05-13T15:22:00+00:00\",\"dateModified\":\"2025-03-18T15:45:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/\"},\"wordCount\":1859,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comicdominicano.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Invincible-una-catarsis-superheroica-moderna.jpg\",\"keywords\":[\"arte secuencial\",\"Invincible\"],\"articleSection\":[\"Arte Secuencial\",\"C\u00f3mic USA\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/\",\"url\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/\",\"name\":\"''Invincible'', una catarsis superheroica moderna - Cultura C\u00f3mic RD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comicdominicano.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Invincible-una-catarsis-superheroica-moderna.jpg\",\"datePublished\":\"2021-05-13T15:22:00+00:00\",\"dateModified\":\"2025-03-18T15:45:48+00:00\",\"description\":\"Catarsis es la facultad de redimir al espectador al proyectarlo en los personajes, ''Invincible'' es un ejemplo de esto en el c\u00f3mic moderno.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comicdominicano.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Invincible-una-catarsis-superheroica-moderna.jpg\",\"contentUrl\":\"https:\\\/\\\/comicdominicano.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Invincible-una-catarsis-superheroica-moderna.jpg\",\"width\":1200,\"height\":675,\"caption\":\"''Invincible'', una catarsis superheroica moderna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comicdominicano.com\\\/invincible-una-catarsis-superheroica-moderna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comicdominicano.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8221;Invincible&#8221;, una catarsis superheroica moderna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/\",\"name\":\"Cultura C\u00f3mic RD\",\"description\":\"Apoyando al C\u00f3mic Dominicano\",\"publisher\":{\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#organization\",\"name\":\"Cultura C\u00f3mic RD\",\"url\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comicdominicano.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/CulturaComicLogo.png\",\"contentUrl\":\"https:\\\/\\\/comicdominicano.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/CulturaComicLogo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Cultura C\u00f3mic RD\"},\"image\":{\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CulturaComicRD\\\/\",\"https:\\\/\\\/x.com\\\/CulturaComic\",\"https:\\\/\\\/www.instagram.com\\\/culturacomic\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18631015\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfrvHQiWywLR4w5v-g3ppjw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zpo.yqp.mybluehost.me\\\/comicdominicano\\\/en\\\/#\\\/schema\\\/person\\\/a5b6cd7bac355962b46feb1abc6ec008\",\"name\":\"Winser Espinal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e6595bbbd60ca53ed33ec864c42eae305f3b7e5fff08f7562d3cce194b4400b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e6595bbbd60ca53ed33ec864c42eae305f3b7e5fff08f7562d3cce194b4400b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e6595bbbd60ca53ed33ec864c42eae305f3b7e5fff08f7562d3cce194b4400b?s=96&d=mm&r=g\",\"caption\":\"Winser Espinal\"},\"description\":\"Como egresado de las carreras Administraci\u00f3n Hotelera menci\u00f3n Mercadeo en PUCMM e Historia del C\u00f3mic en la Universidad Nacional de Singapur, su pasi\u00f3n por el servicio y por el c\u00f3mic lo ha motivado a impulsar una iniciativa de apoyo a los creadores de c\u00f3mics dominicanos, Cultura C\u00f3mic RD. Desde 2015 ha dedicado su tiempo libre a promocionar y conectar a los autores locales con instituciones que compartan su visi\u00f3n de establecer una industria formal del c\u00f3mic en Rep\u00fablica Dominicana que enriquezca culturalmente a nuestro pueblo.\",\"sameAs\":[\"https:\\\/\\\/comicdominicano.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/groups\\\/culturacomicrd\\\/\",\"https:\\\/\\\/www.instagram.com\\\/culturacomic\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/winser-espinal\\\/?locale=es_ES\",\"https:\\\/\\\/x.com\\\/@winserespinal\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfrvHQiWywLR4w5v-g3ppjw\"],\"url\":\"https:\\\/\\\/comicdominicano.com\\\/en\\\/author\\\/winser500\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"''Invincible'', una catarsis superheroica moderna - Cultura C\u00f3mic RD","description":"Catarsis es la facultad de redimir al espectador al proyectarlo en los personajes, ''Invincible'' es un ejemplo de esto en el c\u00f3mic moderno.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comicdominicano.com\/en\/invincible-una-catarsis-superheroica-moderna\/","og_locale":"en_US","og_type":"article","og_title":"''Invincible'', una catarsis superheroica moderna - Cultura C\u00f3mic RD","og_description":"Catarsis es la facultad de redimir al espectador al proyectarlo en los personajes, ''Invincible'' es un ejemplo de esto en el c\u00f3mic moderno.","og_url":"https:\/\/comicdominicano.com\/en\/invincible-una-catarsis-superheroica-moderna\/","og_site_name":"Cultura C\u00f3mic RD","article_publisher":"https:\/\/www.facebook.com\/CulturaComicRD\/","article_author":"https:\/\/www.facebook.com\/groups\/culturacomicrd\/","article_published_time":"2021-05-13T15:22:00+00:00","article_modified_time":"2025-03-18T15:45:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2021\/05\/Invincible-una-catarsis-superheroica-moderna.jpg","type":"image\/jpeg"}],"author":"Winser Espinal","twitter_card":"summary_large_image","twitter_creator":"@winserespinal","twitter_site":"@CulturaComic","twitter_misc":{"Written by":"Winser Espinal","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#article","isPartOf":{"@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/"},"author":{"name":"Winser Espinal","@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#\/schema\/person\/a5b6cd7bac355962b46feb1abc6ec008"},"headline":"&#8221;Invincible&#8221;, una catarsis superheroica moderna","datePublished":"2021-05-13T15:22:00+00:00","dateModified":"2025-03-18T15:45:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/"},"wordCount":1859,"commentCount":0,"publisher":{"@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#organization"},"image":{"@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#primaryimage"},"thumbnailUrl":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2021\/05\/Invincible-una-catarsis-superheroica-moderna.jpg","keywords":["arte secuencial","Invincible"],"articleSection":["Arte Secuencial","C\u00f3mic USA"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/","url":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/","name":"''Invincible'', una catarsis superheroica moderna - Cultura C\u00f3mic RD","isPartOf":{"@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#primaryimage"},"image":{"@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#primaryimage"},"thumbnailUrl":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2021\/05\/Invincible-una-catarsis-superheroica-moderna.jpg","datePublished":"2021-05-13T15:22:00+00:00","dateModified":"2025-03-18T15:45:48+00:00","description":"Catarsis es la facultad de redimir al espectador al proyectarlo en los personajes, ''Invincible'' es un ejemplo de esto en el c\u00f3mic moderno.","breadcrumb":{"@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#primaryimage","url":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2021\/05\/Invincible-una-catarsis-superheroica-moderna.jpg","contentUrl":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2021\/05\/Invincible-una-catarsis-superheroica-moderna.jpg","width":1200,"height":675,"caption":"''Invincible'', una catarsis superheroica moderna"},{"@type":"BreadcrumbList","@id":"https:\/\/comicdominicano.com\/invincible-una-catarsis-superheroica-moderna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comicdominicano.com\/"},{"@type":"ListItem","position":2,"name":"&#8221;Invincible&#8221;, una catarsis superheroica moderna"}]},{"@type":"WebSite","@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#website","url":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/","name":"Cultura C\u00f3mic RD","description":"Apoyando al C\u00f3mic Dominicano","publisher":{"@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#organization","name":"Cultura C\u00f3mic RD","url":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#\/schema\/logo\/image\/","url":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2019\/07\/CulturaComicLogo.png","contentUrl":"https:\/\/comicdominicano.com\/wp-content\/uploads\/2019\/07\/CulturaComicLogo.png","width":2000,"height":2000,"caption":"Cultura C\u00f3mic RD"},"image":{"@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CulturaComicRD\/","https:\/\/x.com\/CulturaComic","https:\/\/www.instagram.com\/culturacomic\/","https:\/\/www.linkedin.com\/company\/18631015\/","https:\/\/www.youtube.com\/channel\/UCfrvHQiWywLR4w5v-g3ppjw"]},{"@type":"Person","@id":"https:\/\/zpo.yqp.mybluehost.me\/comicdominicano\/en\/#\/schema\/person\/a5b6cd7bac355962b46feb1abc6ec008","name":"Winser Espinal","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2e6595bbbd60ca53ed33ec864c42eae305f3b7e5fff08f7562d3cce194b4400b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e6595bbbd60ca53ed33ec864c42eae305f3b7e5fff08f7562d3cce194b4400b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e6595bbbd60ca53ed33ec864c42eae305f3b7e5fff08f7562d3cce194b4400b?s=96&d=mm&r=g","caption":"Winser Espinal"},"description":"Como egresado de las carreras Administraci\u00f3n Hotelera menci\u00f3n Mercadeo en PUCMM e Historia del C\u00f3mic en la Universidad Nacional de Singapur, su pasi\u00f3n por el servicio y por el c\u00f3mic lo ha motivado a impulsar una iniciativa de apoyo a los creadores de c\u00f3mics dominicanos, Cultura C\u00f3mic RD. Desde 2015 ha dedicado su tiempo libre a promocionar y conectar a los autores locales con instituciones que compartan su visi\u00f3n de establecer una industria formal del c\u00f3mic en Rep\u00fablica Dominicana que enriquezca culturalmente a nuestro pueblo.","sameAs":["https:\/\/comicdominicano.com\/","https:\/\/www.facebook.com\/groups\/culturacomicrd\/","https:\/\/www.instagram.com\/culturacomic\/","https:\/\/www.linkedin.com\/in\/winser-espinal\/?locale=es_ES","https:\/\/x.com\/@winserespinal","https:\/\/www.youtube.com\/channel\/UCfrvHQiWywLR4w5v-g3ppjw"],"url":"https:\/\/comicdominicano.com\/en\/author\/winser500\/"}]}},"_links":{"self":[{"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/posts\/2735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/comments?post=2735"}],"version-history":[{"count":4,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/posts\/2735\/revisions"}],"predecessor-version":[{"id":3122,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/posts\/2735\/revisions\/3122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/media\/2736"}],"wp:attachment":[{"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/media?parent=2735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/categories?post=2735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comicdominicano.com\/en\/wp-json\/wp\/v2\/tags?post=2735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}